{"id":27312,"date":"2025-12-09T08:11:11","date_gmt":"2025-12-09T08:11:11","guid":{"rendered":"https:\/\/www.corob.com\/erklaerung-zur-barrierefreiheit\/"},"modified":"2025-12-09T08:11:12","modified_gmt":"2025-12-09T08:11:12","slug":"erklaerung-zur-barrierefreiheit","status":"publish","type":"page","link":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/","title":{"rendered":"Erkl\u00e4rung zur Barrierefreiheit"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:12px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:54;line-height:1;\">Erkl\u00e4rung zur Barrierefreiheit<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>3. Dezember 2025<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\"><h2 class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 36; line-height: 1.1;\" data-fontsize=\"36\" data-lineheight=\"39.6px\">EINLEITUNG<\/h2>\n<p class=\"p3\">Corob S.p.A. hat sich verpflichtet, ihre Website f\u00fcr jede Person ohne Einschr\u00e4nkungen zug\u00e4nglich und nutzbar zu machen. Wir arbeiten kontinuierlich daran, die Inhalte und Funktionen der Website zu verbessern, um die Anforderungen der geltenden Vorschriften und technischen Spezifikationen in \u00dcbereinstimmung mit den in unserem Ethikkodex zum Ausdruck gebrachten Werten zu erf\u00fcllen. <\/p>\n<p class=\"p3\">Diese Seite bietet einen \u00dcberblick \u00fcber den aktuellen Stand der Barrierefreiheit. In einigen F\u00e4llen k\u00f6nnen bestimmte Elemente, Seitenbereiche oder Funktionalit\u00e4ten Verbesserungspotenzial aufweisen: Benutzer k\u00f6nnen diese Probleme wie unten angegeben melden. <\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#dddddd;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><h2><span style=\"background-color: rgba(0, 0, 0, 0);\">ERKL\u00c4RUNG<\/span><\/h2>\n<p class=\"p3\">Corob S.p.A. hat sich verpflichtet, ihre Website in \u00dcbereinstimmung mit dem <strong>Gesetzesdekret Nr. 106\/2018<\/strong>, das die <strong>EU-Richtlinie 2016\/2102<\/strong> umsetzt, und dem <strong>Gesetz Nr. 4 vom 9. Januar 2004<\/strong> f\u00fcr die in Art. 3 Absatz 1-bis genannten Einrichtungen zug\u00e4nglich zu machen. <\/p>\n<p class=\"p3\"><span style=\"background-color: rgba(0, 0, 0, 0);\">Diese Erkl\u00e4rung zur Barrierefreiheit gilt f\u00fcr die Website<\/span> <span class=\"s2\" style=\"background-color: rgba(0, 0, 0, 0);\"><b>www.corob.com<\/b><\/span><span style=\"background-color: rgba(0, 0, 0, 0);\">.<\/span><\/p>\n<h3><b>Konformit\u00e4tsstatus: Teilweise konform<\/b><\/h3>\n<p class=\"p3\">Diese Website ist aufgrund der unten aufgef\u00fchrten Nichtkonformit\u00e4tsprobleme teilweise konform mit den Anforderungen in Anhang A der Norm UNI CEI EN 301549:<\/p>\n<ul>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.1.1<\/b><\/span> \u2013 Nicht alle nicht-textuellen Inhalte, die Benutzern pr\u00e4sentiert werden, haben eine Textalternative, die den gleichen Zweck erf\u00fcllt;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.2.1<\/b><\/span> \u2013 In einigen reinen Audio- oder reinen Video-Medien werden gleichwertige Informationen nicht in einem alternativen Format bereitgestellt;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.3.1<\/b><\/span> \u2013 In einigen F\u00e4llen k\u00f6nnen Informationen, Strukturen oder Beziehungen, die durch die Pr\u00e4sentation vermittelt werden, nicht programmgesteuert ermittelt werden (oder sind nicht als Text verf\u00fcgbar);<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.3.2<\/b><\/span> \u2013 Sinnvolle Reihenfolge: Die Lesereihenfolge folgt in einigen Abschnitten nicht vollst\u00e4ndig der logisch-visuellen Reihenfolge;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.3.3<\/b><\/span> \u2013 Sensorische Eigenschaften: Einige Anweisungen beziehen sich ausschlie\u00dflich auf visuelle Eigenschaften (z. B. \u201esiehe rechts\u201c), ohne Alternativen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.3.4<\/b><\/span> \u2013 Die Anzeige und der Betrieb bestimmter Inhalte \u00e4ndern sich nicht in Abh\u00e4ngigkeit von der Bildschirmausrichtung;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.3.5<\/b><\/span> \u2013 Der Zweck einiger Eingabefelder, die bestimmte Daten akzeptieren, wird assistierenden Technologien nicht korrekt mitgeteilt oder ist nicht ordnungsgem\u00e4\u00df implementiert;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.1<\/b><\/span> \u2013 In einigen F\u00e4llen wird Farbe allein verwendet, um einen Zweck zu identifizieren oder Informationen oder Funktionen zu unterscheiden;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.2<\/b><\/span> \u2013 Audioinhalte k\u00f6nnen l\u00e4nger als drei Sekunden automatisch abgespielt werden, ohne eine M\u00f6glichkeit zu bieten, das Audio zu pausieren, zu stoppen oder unabh\u00e4ngig von den Systemeinstellungen zu steuern;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.3<\/b><\/span> \u2013 Die visuelle Darstellung von Text und Bildern, die Text enthalten, erf\u00fcllt nicht immer das erforderliche Mindestkontrastverh\u00e4ltnis, mit Ausnahmen, die durch die Verordnung zul\u00e4ssig sind (z. B. Logos);<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.4<\/b><\/span> \u2013 Einige Texte (mit Ausnahme von Beschriftungen und Bildern, die Text enthalten) k\u00f6nnen nicht ohne assistierende Technologie und ohne Verlust von Inhalt oder Funktionalit\u00e4t auf bis zu 200 % vergr\u00f6\u00dfert werden;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.5<\/b><\/span> \u2013 In einigen F\u00e4llen werden Textbilder anstelle von Klartext verwendet und sind weder anpassbar noch wesentlich f\u00fcr die vermittelten Informationen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.10<\/b><\/span> \u2013 Inhalte, die kein zweidimensionales Layout erfordern (z. B. Datentabellen, Karten), flie\u00dfen nicht um, wenn die Gr\u00f6\u00dfe des Viewports des User Agents ge\u00e4ndert wird;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.11<\/b><\/span> \u2013 F\u00fcr bestimmte wesentliche Komponenten \u00fcberschreitet der Farbkontrast zu benachbarten Elementen nicht das Verh\u00e4ltnis 3:1;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.12<\/b><\/span> \u2013 Beim \u00c4ndern des Textabstands \u2013 Zeilenh\u00f6he, Absatzabstand, Buchstaben- oder Wortabstand \u2013 kann es zu einem Verlust von Informationen oder Inhalten kommen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.1.4.13<\/b><\/span> \u2013 Bei Aktivierung (Hover\/Fokus): In einigen F\u00e4llen erf\u00fcllen Inhalte, die beim Hovern oder beim Tastaturfokus angezeigt werden, keine Kriterien wie Persistenz oder Abweisbarkeit;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.1.1<\/b><\/span> \u2013 Einige Funktionalit\u00e4ten sind nicht vollst\u00e4ndig \u00fcber die Tastatur (oder eine \u00e4hnliche Eingabeschnittstelle) bedienbar;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.2.1<\/b><\/span> \u2013 Bestimmte zeitabh\u00e4ngige Elemente erlauben Folgendes nicht: Deaktivieren von Zeitlimits, Anpassen derselben, Verl\u00e4ngern derselben um das Zehnfache oder Benachrichtigen von Benutzern vor Ablauf der Zeit;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.2.2<\/b><\/span> \u2013 Bestimmte Animationen, blinkende Inhalte, automatisches Scrollen oder automatisch aktualisierte Informationen, die l\u00e4nger als f\u00fcnf Sekunden dauern oder gleichzeitig mit anderen Inhalten angezeigt werden, k\u00f6nnen nicht pausiert oder ausgeblendet werden;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.3.1<\/b><\/span> \u2013 Einige Animationen oder blinkende Inhalte k\u00f6nnen Schwellenwerte \u00fcberschreiten, die dazu bestimmt sind, fotosensitive epileptische Anf\u00e4lle zu verhindern;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.1<\/b><\/span> \u2013 Es ist kein Mechanismus verf\u00fcgbar, um wiederholte Inhaltsbl\u00f6cke zu \u00fcberspringen, die in mehreren Abschnitten erscheinen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.2<\/b><\/span> \u2013 Einige Webseiten haben keine Titel, die ihren Zweck oder ihr Thema beschreiben;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.3<\/b><\/span> \u2013 In einigen sequenziell navigierbaren Abschnitten folgen bestimmte fokussierbare Objekte keiner logischen Reihenfolge, die Bedeutung und Bedienbarkeit bewahrt;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.4<\/b><\/span> \u2013 Der Zweck einiger Links kann nicht allein aus ihrem Text oder aus Text plus angrenzendem Inhalt ermittelt werden;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.5<\/b><\/span> \u2013 In einigen Abschnitten sind m\u00f6glicherweise nicht mehrere M\u00f6glichkeiten verf\u00fcgbar, um Webseiten innerhalb der Website zu finden;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.6<\/b><\/span> \u2013 \u00dcberschriften und Beschriftungen verdeutlichen nicht immer ausreichend Inhalt oder Funktion;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.4.7<\/b><\/span> \u2013 Einige interaktive Elemente haben keine sichtbare Fokusanzeige;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.5.1<\/b><\/span> \u2013 Bestimmte Funktionen, die auf Mehrfingergesten oder pfadbasierten Gesten basieren, sind m\u00f6glicherweise nicht vollst\u00e4ndig mit einer einzelnen Zeigereingabe bedienbar;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.5.2<\/b><\/span> \u2013 Bei einigen Einzelzeigeraktionen kann das Down-Ereignis eine Funktionalit\u00e4t ausl\u00f6sen, ohne eine M\u00f6glichkeit zu bieten, die Aktion vor der Freigabe abzubrechen, r\u00fcckg\u00e4ngig zu machen oder zu stoppen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.5.3<\/b><\/span> \u2013 In einigen F\u00e4llen ist die sichtbare Beschriftung einer Benutzeroberfl\u00e4chenkomponente nicht in ihrem zug\u00e4nglichen Namen enthalten, was das Verst\u00e4ndnis f\u00fcr assistierende Technologien zur Sprachsteuerung erschwert;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.2.5.4<\/b><\/span> \u2013 Die Funktionalit\u00e4t kann durch Ger\u00e4tebewegung ausgel\u00f6st werden (z. B. Sch\u00fctteln, um die Aktion r\u00fcckg\u00e4ngig zu machen);<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.1.1<\/b><\/span> \u2013 Die Standardsprache bestimmter Seiten oder Abschnitte ist m\u00f6glicherweise nicht ordnungsgem\u00e4\u00df im Code deklariert;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.2.1<\/b><\/span> \u2013 Einige Benutzeroberfl\u00e4chenkomponenten k\u00f6nnen unerwartet eine Kontext\u00e4nderung ausl\u00f6sen, wenn sie den Fokus erhalten;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.2.2<\/b><\/span> \u2013 In einigen Abschnitten kann das \u00c4ndern einer Benutzeroberfl\u00e4chenkomponente eine automatische Kontext\u00e4nderung ohne vorherige Benachrichtigung des Benutzers verursachen;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.2.3<\/b><\/span> \u2013 Einige Navigationsmechanismen, die auf mehreren Webseiten wiederholt werden, erscheinen nicht in der gleichen Reihenfolge;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.2.4<\/b><\/span> \u2013 Einige Komponenten, die auf mehreren Webseiten die gleiche Funktion ausf\u00fchren, werden nicht einheitlich identifiziert;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.3.1<\/b><\/span> \u2013 Fehleridentifizierung in Formularen: Nicht alle Eingabefehler werden klar kommuniziert;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.3.2<\/b><\/span> \u2013 In einigen F\u00e4llen werden keine Beschriftungen oder Anweisungen bereitgestellt, wenn Benutzereingabeaktionen erforderlich sind;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.3.3<\/b><\/span> \u2013 Wenn Eingabefehler erkannt werden und Vorschl\u00e4ge zur Korrektur bekannt sind, werden diese Vorschl\u00e4ge nicht immer bereitgestellt;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.3.3.4<\/b><\/span> \u2013 Auf Webseiten, die rechtliche Verpflichtungen oder Finanztransaktionen beinhalten, bei denen Benutzer Daten verwalten, \u00e4ndern oder l\u00f6schen k\u00f6nnen, ist m\u00f6glicherweise keine der folgenden Aktionen m\u00f6glich: Aktionen r\u00fcckg\u00e4ngig machen, Informationen vor der endg\u00fcltigen \u00dcbermittlung \u00fcberpr\u00fcfen oder Daten korrigieren;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.4.1.1<\/b><\/span> \u2013 Das Seiten-Markup entspricht nicht immer den Spezifikationen oder enth\u00e4lt Fehler oder doppelte Attribute\/IDs;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.4.1.2<\/b><\/span> \u2013 In einigen F\u00e4llen haben UI-Komponenten (Formularelemente, Links, skriptgenerierte Komponenten usw.) keine genauen oder richtig eingestellten Namen, Rollen, Zust\u00e4nde, Eigenschaften oder Werte, noch werden Benutzer\/assistierende Technologien benachrichtigt, wenn sich diese \u00e4ndern;<\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>C.9.4.1.3<\/b><\/span> \u2013 Statusmeldungen werden nicht immer auf eine Weise verf\u00fcgbar gemacht, die von assistierenden Technologien interpretiert werden kann, ohne den Fokus zu verschieben.<\/p>\n<\/li>\n<\/ul>\n<h3><b> <\/b><\/h3>\n<h3><b>Dokumente<\/b><\/h3>\n<p class=\"p3\">Alle herunterladbaren PDF-Dokumente auf der Website sind f\u00fcr Bildschirmleseprogramme nur teilweise lesbar, da ihnen eine hierarchische Struktur (Inhaltsverzeichnis, \u00dcberschriften, interne Links) und Textalternativen fehlen.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#dddddd;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-4\"><h2>ERSTELLUNG DIESER ERKL\u00c4RUNG ZUR BARRIEREFREIHEIT<\/h2>\n<p class=\"p3\">Diese Erkl\u00e4rung wurde am <span class=\"s2\"><b>3. Dezember 2025<\/b><\/span> erstellt.<\/p>\n<p class=\"p3\">Die Informationen in dieser Erkl\u00e4rung basieren auf einer Selbsteinsch\u00e4tzung, die direkt vom Dienstanbieter auf allen Hauptseiten der Website durchgef\u00fchrt wurde.<\/p>\n<p class=\"p3\">Die Erkl\u00e4rung wurde zuletzt am <span class=\"s2\"><b>3. Dezember 2025<\/b><\/span> \u00fcberpr\u00fcft, in \u00dcbereinstimmung mit der Empfehlung, die Richtigkeit der in dieser Erkl\u00e4rung zur Barrierefreiheit enthaltenen Informationen regelm\u00e4\u00dfig (mindestens j\u00e4hrlich) zu \u00fcberpr\u00fcfen.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#dddddd;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-5\"><h2>FEEDBACK UND KONTAKTINFORMATIONEN<\/h2>\n<p class=\"p3\">Corob S.p.A. bietet einen Feedback-Mechanismus zur Meldung von F\u00e4llen von Nichteinhaltung und zur Anforderung von Informationen oder Inhalten, die nicht in den Geltungsbereich der Richtlinie fallen.<\/p>\n<p class=\"p3\">Benutzer k\u00f6nnen Barrierefreiheitsprobleme oder F\u00e4lle von Nichteinhaltung per E-Mail melden an: <span class=\"s2\"><b>info@corob.com<\/b><b><\/b><\/span><\/p>\n<p class=\"p3\">Bitte geben Sie bei der Kontaktaufnahme Folgendes an:<\/p>\n<ul>\n<li>\n<p class=\"p1\">Vollst\u00e4ndiger Name;<\/p>\n<\/li>\n<li>\n<p class=\"p1\">URL der Seite oder des Abschnitts der betroffenen Website\/App;<\/p>\n<\/li>\n<li>\n<p class=\"p1\">Klare und pr\u00e4gnante Beschreibung des aufgetretenen Problems;<\/p>\n<\/li>\n<li>\n<p class=\"p1\">Verwendete Tools (Betriebssystem, Browser, assistierende Technologien).<\/p>\n<\/li>\n<\/ul>\n<p class=\"p3\">Bitte beschreiben Sie das Problem, ohne sensible Daten bez\u00fcglich Ihrer Behinderung anzugeben.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#dddddd;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-6\"><h2>EINREICHEN VON BERICHTEN AN AGID<\/h2>\n<p class=\"p3\">Wenn die Antwort innerhalb von drei\u00dfig Tagen nach der Benachrichtigung oder Anfrage unbefriedigend oder nicht vorhanden ist, k\u00f6nnen Einzelpersonen einen Bericht an AgID per zertifizierter E-Mail (PEC) senden an: <span class=\"s2\"><b>protocollo@pec.agid.gov.it<\/b><b><\/b><\/span><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;width:100%;\"><div class=\"fusion-separator-border sep-single\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#dddddd;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-7\"><h2>WEBSITE-INFORMATIONEN<\/h2>\n<ol start=\"1\">\n<li>\n<p class=\"p1\"><b>Ver\u00f6ffentlichungsdatum:<\/b><span class=\"s1\"> April 2025<\/span><\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>Durchgef\u00fchrte Usability-Tests:<\/b><\/span> Ja. Die Bewertung wurde durch Selbsteinsch\u00e4tzung mit automatischen Tools (mauve++) und durch Bediener durchgef\u00fchrt. Es wurden bis zu 10 Seiten bewertet, einschlie\u00dflich der Homepage in einer Tiefe von 1 Ebene.  <\/p>\n<\/li>\n<li>\n<p class=\"p1\"><span class=\"s1\"><b>Verwendetes CMS:<\/b><\/span> WordPress<\/p>\n<\/li>\n<\/ol>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-27312","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COROB-Datenschutzerkl\u00e4rung<\/title>\n<meta name=\"description\" content=\"Lesen Sie die COROB-Datenschutzerkl\u00e4rung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COROB-Datenschutzerkl\u00e4rung\" \/>\n<meta property=\"og:description\" content=\"Lesen Sie die COROB-Datenschutzerkl\u00e4rung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/\" \/>\n<meta property=\"og:site_name\" content=\"COROB\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T08:11:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/erklaerung-zur-barrierefreiheit\\\/\",\"url\":\"https:\\\/\\\/www.corob.com\\\/de\\\/erklaerung-zur-barrierefreiheit\\\/\",\"name\":\"COROB-Datenschutzerkl\u00e4rung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#website\"},\"datePublished\":\"2025-12-09T08:11:11+00:00\",\"dateModified\":\"2025-12-09T08:11:12+00:00\",\"description\":\"Lesen Sie die COROB-Datenschutzerkl\u00e4rung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/erklaerung-zur-barrierefreiheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.corob.com\\\/de\\\/erklaerung-zur-barrierefreiheit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/erklaerung-zur-barrierefreiheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.corob.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erkl\u00e4rung zur Barrierefreiheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.corob.com\\\/de\\\/\",\"name\":\"COROB\",\"description\":\"High-tech dispensing and mixing solutions for paints and coatings systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.corob.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#organization\",\"name\":\"COROB\",\"url\":\"https:\\\/\\\/www.corob.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.corob.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/COROB-240.png\",\"contentUrl\":\"https:\\\/\\\/www.corob.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/COROB-240.png\",\"width\":240,\"height\":73,\"caption\":\"COROB\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corob.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/corob\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCxnFt4FEhuhdm87NAb27qBQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COROB-Datenschutzerkl\u00e4rung","description":"Lesen Sie die COROB-Datenschutzerkl\u00e4rung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/","og_locale":"de_DE","og_type":"article","og_title":"COROB-Datenschutzerkl\u00e4rung","og_description":"Lesen Sie die COROB-Datenschutzerkl\u00e4rung","og_url":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/","og_site_name":"COROB","article_modified_time":"2025-12-09T08:11:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/","url":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/","name":"COROB-Datenschutzerkl\u00e4rung","isPartOf":{"@id":"https:\/\/www.corob.com\/de\/#website"},"datePublished":"2025-12-09T08:11:11+00:00","dateModified":"2025-12-09T08:11:12+00:00","description":"Lesen Sie die COROB-Datenschutzerkl\u00e4rung","breadcrumb":{"@id":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.corob.com\/de\/erklaerung-zur-barrierefreiheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.corob.com\/de\/"},{"@type":"ListItem","position":2,"name":"Erkl\u00e4rung zur Barrierefreiheit"}]},{"@type":"WebSite","@id":"https:\/\/www.corob.com\/de\/#website","url":"https:\/\/www.corob.com\/de\/","name":"COROB","description":"High-tech dispensing and mixing solutions for paints and coatings systems","publisher":{"@id":"https:\/\/www.corob.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.corob.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.corob.com\/de\/#organization","name":"COROB","url":"https:\/\/www.corob.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.corob.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.corob.com\/wp-content\/uploads\/2020\/01\/COROB-240.png","contentUrl":"https:\/\/www.corob.com\/wp-content\/uploads\/2020\/01\/COROB-240.png","width":240,"height":73,"caption":"COROB"},"image":{"@id":"https:\/\/www.corob.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/corob\/","https:\/\/www.youtube.com\/channel\/UCxnFt4FEhuhdm87NAb27qBQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/pages\/27312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/comments?post=27312"}],"version-history":[{"count":2,"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/pages\/27312\/revisions"}],"predecessor-version":[{"id":27314,"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/pages\/27312\/revisions\/27314"}],"wp:attachment":[{"href":"https:\/\/www.corob.com\/de\/wp-json\/wp\/v2\/media?parent=27312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}